{"id":603,"count":1,"description":"","link":"https:\/\/buymlocal.com\/blog\/tag\/softwaredeliverygovernanceplatform\/","name":"#SoftwareDeliveryGovernancePlatform","slug":"softwaredeliverygovernanceplatform","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/buymlocal.com\/blog\/wp-json\/wp\/v2\/tags\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/buymlocal.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/buymlocal.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/buymlocal.com\/blog\/wp-json\/wp\/v2\/posts?tags=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}